{"id":44244,"date":"2023-02-07T12:16:00","date_gmt":"2023-02-07T12:16:00","guid":{"rendered":"https:\/\/knowhow.distrelec.com\/?p=44244"},"modified":"2023-02-07T12:16:06","modified_gmt":"2023-02-07T12:16:06","slug":"comunicazione-di-dati-in-ambienti-difficili","status":"publish","type":"post","link":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/","title":{"rendered":"Comunicazione di dati in ambienti difficili"},"content":{"rendered":"\n<p>Oggi, grazie alla tecnologia avanzata e all&#8217;Industrial Internet of Things (IIoT), gli impianti e i siti industriali possono essere monitorati in modo adeguato. Grazie a controlli elettronici, componenti di rilevamento e prodotti automatizzati, \u00e8 possibile rilevare i disturbi.&nbsp;<\/p>\n\n\n\n<p>Esistono diversi tipi d&#8217;interruzione che possono verificarsi e avere un impatto sulla comunicazione dei dati. I dispositivi e le connessioni possono essere disturbati da condizioni atmosferiche, lunga latenza, basso rapporto segnale\/rumore, problemi di connessione, forti vibrazioni, alta pressione e altri disturbi.<\/p>\n\n\n\n<p>Oggi l&#8217;attenzione si concentra sugli ambienti difficili, come temperature estreme, umidit\u00e0 corrosiva o fuoriuscite di carburante. Questo articolo fornisce alcuni esempi e dei prodotti per garantire il corretto scambio di dati tra le macchine in condizioni estreme.<\/p>\n\n\n\n<h2 id=\"iiot-contro-gli-ambienti-difficili\" class=\"wp-block-heading\">IIoT contro gli ambienti difficili<\/h2>\n\n\n\n<p>La capacit\u00e0 dei produttori di mantenere le linee di produzione e di monitorare adeguatamente gli impianti in un ambiente in rapida evoluzione e perturbato pu\u00f2 richiedere tempo e sforzi. Fortunatamente, l&#8217;Industrial IoT e l&#8217;AI sono di grande aiuto anche in ambienti difficili. La manutenzione predittiva, che spesso si concentra sulle aree di guasto, \u00e8 superata dai sistemi di salute delle macchine che raccolgono dati IoT industriali e li valutano utilizzando algoritmi di intelligenza artificiale. I sistemi autonomi adeguati devono essere in grado di resistere a queste condizioni quando l&#8217;elettronica deve operare in ambienti industriali o a temperature estreme, che possono anche contenere campi magnetici ed elettrici distruttivi.&nbsp;<\/p>\n\n\n\n<p>Un marchio che fornisce prodotti specificamente progettati per raccogliere dati importanti indipendentemente dalle condizioni atmosferiche \u00e8 <a href=\"https:\/\/www.distrelec.it\/it\/manufacturer\/brainboxes\/man_brx\" target=\"_blank\" rel=\"noreferrer noopener\">Brainboxes<\/a>. Brainboxes fornisce soluzioni hardware per il monitoraggio delle macchine e i progetti Industrial IoT. Con un team di progettisti software e hardware altamente qualificati dal 1984, Brainboxes ha creato, prodotto e supportato le proprie tecnologie di base. Questo ha reso il marchio uno dei principali produttori mondiali di dispositivi di comunicazione industriale.<\/p>\n\n\n\n<h2 id=\"il-funzionamento-delle-macchine-in-condizioni-estreme-come-e-possibile\" class=\"wp-block-heading\">Il funzionamento delle macchine in condizioni estreme: come \u00e8 possibile?<\/h2>\n\n\n\n<p>L&#8217;installazione e il collegamento delle apparecchiature sono incredibilmente impegnativi, poich\u00e9 specifici dispositivi elettronici o di rilevamento possono agire in modo diverso in ambienti industriali difficili. La longevit\u00e0 del sistema dipende dal luogo di raccolta dei dati e dal dispositivo utilizzato. Alcuni esempi di condizioni difficili nelle applicazioni industriali includono temperature estreme, impatti fisici, scariche elettrostatiche (ESD), vibrazioni e interferenze elettromagnetiche (EMI).&nbsp;<\/p>\n\n\n\n<p>I macchinari abilitati all&#8217;IIoT sono la soluzione per prevenire i danni. I dispositivi tecnologici avanzati sono dotati di sensori e software in grado di raccogliere e organizzare i dati indipendentemente dagli ambienti industriali difficili. Ad esempio, i nuovi prodotti automatizzati di Brainbox, come gli <a href=\"https:\/\/www.distrelec.it\/it\/industrial-ethernet-switches-unmanaged-sw-brainboxes\/pf\/3476101\" target=\"_blank\" rel=\"noreferrer noopener\">switch ethernet industriali<\/a> o i <a href=\"https:\/\/www.distrelec.it\/it\/ethernet-media-converters-ed-brainboxes\/pf\/3476143\" target=\"_blank\" rel=\"noreferrer noopener\">moduli di ingresso analogici<\/a> che consentono di monitorare i componenti chiave del sistema automatico, sono progettati per raccogliere misurazioni in remoto durante tutto l&#8217;anno. In che modo? Continuate a leggere per scoprirlo.<\/p>\n\n\n\n<h3 id=\"automazione-in-antartide\" class=\"wp-block-heading\">Automazione in Antartide<\/h3>\n\n\n\n<p>Nell&#8217;Antartico, le temperature invernali tipiche scendono al di sotto di -20 fino a minime estreme di -55. Inoltre, ci sono 105 giorni di buio completo. Nonostante ci\u00f2, i dati vengono raccolti da una stazione.<\/p>\n\n\n\n<p>In una regione sensibile al clima, la stazione di ricerca di Halley \u00e8 un&#8217;importante piattaforma mondiale per il monitoraggio del tempo terrestre, aereo e spaziale. La Halley VI del Mare di Weddell \u00e8 la prima stazione di ricerca mobile al mondo, costruita in cima a una piattaforma di ghiaccio galleggiante. Gli scienziati possono indagare su questioni globali urgenti, tra cui il cambiamento climatico e l&#8217;innalzamento del livello del mare, nonch\u00e9 il tempo spaziale e il buco dell&#8217;ozono, che \u00e8 stato originariamente identificato ad Halley nel 1985, grazie alla ricerca pluripremiata e all&#8217;avanguardia del moderno laboratorio e degli alloggi della stazione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  height=\"432\"  width=\"1024\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAGwAQMAAAANIYUSAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAExJREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8G2bAAAZlDTS0AAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-42403 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/image-10-1024x432.png\" ><figcaption>Immagine 1: Stazione di ricerca Halley VI sulla piattaforma di ghiaccio Brunt in Antartide. Fonte: Servizio antartico britannico<\/figcaption><\/figure>\n\n\n\n<p>La stazione \u00e8 dotata di un sistema innovativo di alimentazione autonoma sviluppato dagli ingegneri del British Antarctic Survey (BAS). Questo sistema permette al team del BAS di ottenere queste misurazioni senza l&#8217;aiuto del personale a terra, costruendo un sistema di alimentazione autonoma all&#8217;avanguardia con alimentazione continua e immissione di dati.&nbsp;<\/p>\n\n\n\n<p>La stazione \u00e8 dotata di una microturbina. \u00c8 la prima volta che una microturbina viene installata in Antartide per alimentare autonomamente la strumentazione. Grazie a ci\u00f2, la sede centrale di BAS a Cambridge, nel Regno Unito, pu\u00f2 monitorare, controllare e spegnere il sistema da remoto. Gli ingegneri del BAS hanno installato il generatore a microturbina Capstone a causa della regolare manutenzione mensile richiesta dalla tecnologia tradizionale dei generatori diesel. Il generatore pu\u00f2 funzionare senza alcuna manutenzione durante l&#8217;inverno, poich\u00e9 pu\u00f2 durare nove mesi tra una riparazione e l&#8217;altra.<\/p>\n\n\n\n<p>All&#8217;interno della microturbina \u00e8 presente un <a href=\"https:\/\/www.distrelec.com\/global\/?search=30220119\" target=\"_blank\" rel=\"noreferrer noopener\">modulo di ingresso analogico Brainboxes<\/a> che raccoglie misure di alta precisione di tensioni e correnti in ambienti difficili per tutto l&#8217;anno. Questi moduli prendono i segnali del mondo reale e li trasformano in dati leggibili che sono disponibili in tempo reale per gli ingegneri della rete che si estende per oltre 10.000 miglia in tutto il mondo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"795\"  height=\"450\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAxsAAAHCAQMAAAC9vkZEAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAENJREFUeNrtwYEAAAAAw6D5U1\/hAFUBAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAALwGsYoAAaRlbhAAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-42420 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 795px) 100vw, 795px\"  data-pk-src=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/British-Antarctic-Surveys-Halley-VI-Research-Station.png\"  data-pk-srcset=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/British-Antarctic-Surveys-Halley-VI-Research-Station.png 795w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/British-Antarctic-Surveys-Halley-VI-Research-Station.png?resize=300,170 300w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/British-Antarctic-Surveys-Halley-VI-Research-Station.png?resize=768,435 768w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/British-Antarctic-Surveys-Halley-VI-Research-Station.png?resize=380,215 380w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/British-Antarctic-Surveys-Halley-VI-Research-Station.png?resize=550,311 550w\" ><figcaption>Immagine 2: Stazione di ricerca Halley VI del British Antarctic Survey. Fonte: Brainboxes<\/figcaption><\/figure>\n\n\n\n<p>I moduli di ingresso analogici di Brainboxes sono utilizzati per monitorare i sensori di livello del serbatoio del carburante e per misurare il flusso di carburante, posizionati all&#8217;interno della microturbina (immagine 2). Questa \u00e8 stata la parte pi\u00f9 impegnativa del sistema da gestire in remoto e garantire una temperatura stabile all&#8217;interno del suo alloggiamento \u00e8 stato essenziale, poich\u00e9 i serbatoi esterni contenenti circa 50 m3 di carburante necessitavano in media di 140 litri al giorno per essere pompati nella microturbina. Tuttavia, il BAS pu\u00f2 garantire i livelli corretti monitorando le fuoriuscite di carburante in tempo reale grazie all&#8217;accesso a un complesso cruscotto di monitoraggio che mostra: dati sul carburante, livelli, pressioni e posizioni delle valvole.<\/p>\n\n\n\n<h2 id=\"conclusione\" class=\"wp-block-heading\">Conclusione<\/h2>\n\n\n\n<p><a href=\"https:\/\/knowhow.distrelec.com\/it\/tecnologie-informatiche-e-digitali\/ai-e-machine-learning-nella-cybersecurity-e-nella-sicurezza-industriale\/\" target=\"_blank\" rel=\"noreferrer noopener\">L&#8217;apprendimento automatico e l&#8217;intelligenza artificiale possono aiutare a combattere i rischi imprevisti<\/a> e a proteggere lo scambio di dati, quindi svolgono un ruolo fondamentale nella lotta alle interruzioni. \u00c8 per questo che molti dispositivi vengono controllati da remoto, senza la necessit\u00e0 di personale che li sorvegli nello stesso luogo. Come abbiamo presentato sopra, un sistema BAS che ha funzionato a temperature fino a -55&#8217;C \u00e8 in funzione da quasi 2 anni, con il personale presente in stazione solo nei mesi estivi. Con i moduli Remote IO di Brainbox, \u00e8 possibile monitorare i componenti chiave del sistema di automazione indipendentemente dalle condizioni estreme.<\/p>\n\n\n\n<p>Date un&#8217;occhiata al modello 3D del Centro di Ricerca Halley VI <a href=\"https:\/\/my.matterport.com\/show\/?m=FwqkctaNU8o\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a>.<\/p>\n\n\n\n<h2 id=\"prodotti-consigliati\" class=\"wp-block-heading\">Prodotti consigliati<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>IO remoto, Brainbox<\/strong><\/p>\n\n\n\n<p>Caratteristiche:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>8 canali differenziali programmabili individualmente<\/li><li>Tutti i tipi di sensori possono essere collegati agli ingressi 0-10V e 4-20mA.<\/li><li>Automazione di fabbrica e controllo di processo, montaggio su guida DIN integrato <\/li><li>Campo di temperatura da 40\u00b0C a +80\u00b0C &#8211; Monitoraggio istantaneo da qualsiasi browser web<\/li><li>Con un amplificatore di guadagno programmabile \u00e8 possibile effettuare misure a piena risoluzione fino a 75mV.<\/li><\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img  loading=\"lazy\"  decoding=\"async\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-42454 pk-lazyload\"  width=\"255\"  height=\"142\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 255px) 100vw, 255px\"  data-pk-src=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg\"  data-pk-srcset=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg 1020w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg?resize=300,168 300w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg?resize=768,429 768w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg?resize=380,212 380w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg?resize=550,307 550w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-ED-549-30220119-01.jpg?resize=800,447 800w\" ><\/figure><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-red-background-color has-background\" href=\"https:\/\/www.distrelec.com\/global\/?search=30220119\" target=\"_blank\" rel=\"noreferrer noopener\"><strong> Acquista ora<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Switch Ethernet industriali, Brainbox<\/strong><\/p>\n\n\n\n<p>Caratteristiche:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Montaggio su guida DIN integrato&nbsp;<\/li><li>Switch Ethernet temprato a 8 porte<\/li><li>Doppio ingresso di alimentazione ridondante: da 5 a 30 volt CC<\/li><li>Non \u00e8 necessario alcun software.&nbsp;<\/li><li>Intervallo di temperatura operativa industriale: da -40\u00b0C a +80\u00b0C\/da -40\u00b0F a +176\u00b0F.<\/li><li>Assistenza e garanzia&nbsp;<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1020\"  height=\"570\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAA\/wAAAI6AQMAAACgqdGlAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF1JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAvBsfSQABeZS+xAAAAABJRU5ErkJggg==\"  alt=\"\"  class=\"wp-image-42437 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1020px) 100vw, 1020px\"  data-pk-src=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg\"  data-pk-srcset=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg 1020w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg?resize=300,168 300w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg?resize=768,429 768w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg?resize=380,212 380w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg?resize=550,307 550w, https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Brainboxes-SW-708-30220131-01.jpg?resize=800,447 800w\" ><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-red-background-color has-background\" href=\"https:\/\/www.distrelec.com\/global\/?search=30220131\" target=\"_blank\" rel=\"noreferrer noopener\"><strong> Acquista ora<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Oggi, grazie alla tecnologia avanzata e all&#8217;Industrial Internet of Things (IIoT), gli impianti e i siti industriali possono&hellip;\n","protected":false},"author":16,"featured_media":42497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_singular_sidebar":"","csco_page_header_type":"","csco_appearance_grid":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1019,1007,205],"tags":[],"coauthors":[],"class_list":{"0":"post-44244","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-automazione","8":"category-internet-delle-cose-iot","9":"category-stem-e-istruzione","10":"cs-entry","11":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comunicazione di dati in ambienti difficili - KnowHow<\/title>\n<meta name=\"description\" content=\"Lo scambio di dati in ambienti difficili pu\u00f2 essere problematico, poich\u00e9 alcuni dispositivi potrebbero non funzionare bene a temperature estreme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicazione di dati in ambienti difficili - KnowHow\" \/>\n<meta property=\"og:description\" content=\"Lo scambio di dati in ambienti difficili pu\u00f2 essere problematico, poich\u00e9 alcuni dispositivi potrebbero non funzionare bene a temperature estreme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\" \/>\n<meta property=\"og:site_name\" content=\"KnowHow\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-07T12:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-07T12:16:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Justyna Matuszak\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Justyna Matuszak\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Justyna Matuszak\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\"},\"author\":{\"name\":\"Justyna Matuszak\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/person\/0f190c371d7aa3b29340b10882910edb\"},\"headline\":\"Comunicazione di dati in ambienti difficili\",\"datePublished\":\"2023-02-07T12:16:00+00:00\",\"dateModified\":\"2023-02-07T12:16:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\"},\"wordCount\":1179,\"publisher\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png\",\"articleSection\":[\"Automazione\",\"Internet delle Cose (IoT)\",\"STEM e istruzione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\",\"url\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\",\"name\":\"Comunicazione di dati in ambienti difficili - KnowHow\",\"isPartOf\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png\",\"datePublished\":\"2023-02-07T12:16:00+00:00\",\"dateModified\":\"2023-02-07T12:16:06+00:00\",\"description\":\"Lo scambio di dati in ambienti difficili pu\u00f2 essere problematico, poich\u00e9 alcuni dispositivi potrebbero non funzionare bene a temperature estreme.\",\"breadcrumb\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage\",\"url\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png\",\"contentUrl\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\/\/knowhow.distrelec.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicazione di dati in ambienti difficili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#website\",\"url\":\"https:\/\/knowhow.distrelec.com\/it\/\",\"name\":\"KnowHow\",\"description\":\"KnowHow Hub\",\"publisher\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/knowhow.distrelec.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#organization\",\"name\":\"Distrelec\",\"url\":\"https:\/\/knowhow.distrelec.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2021\/09\/distrelec_logo.png\",\"contentUrl\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2021\/09\/distrelec_logo.png\",\"width\":530,\"height\":98,\"caption\":\"Distrelec\"},\"image\":{\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/person\/0f190c371d7aa3b29340b10882910edb\",\"name\":\"Justyna Matuszak\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/person\/image\/9a432b6fa69e68c439c1a2d8acf914c3\",\"url\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2024\/02\/cropped-Justyna-scaled-3-96x96.jpg\",\"contentUrl\":\"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2024\/02\/cropped-Justyna-scaled-3-96x96.jpg\",\"caption\":\"Justyna Matuszak\"},\"description\":\"Justyna, as a Digital Content Writer at Distrelec, is responsible for writing and managing content on KnowHow. She studied Journalism and Social Communication with a specialisation in social media and e-PR. In that time, she participated in journalist internships in Wroclaw (PL) and London. She is passionate about innovations, the digital world and the impact technology has on our lives. Her interests are sport, music and film photography.\",\"sameAs\":[\"http:\/\/www.distrelec.com\",\"https:\/\/uk.linkedin.com\/in\/justyna-matuszak-217b51172\"],\"url\":\"https:\/\/knowhow.distrelec.com\/it\/author\/justyna-matusza\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicazione di dati in ambienti difficili - KnowHow","description":"Lo scambio di dati in ambienti difficili pu\u00f2 essere problematico, poich\u00e9 alcuni dispositivi potrebbero non funzionare bene a temperature estreme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/","og_locale":"it_IT","og_type":"article","og_title":"Comunicazione di dati in ambienti difficili - KnowHow","og_description":"Lo scambio di dati in ambienti difficili pu\u00f2 essere problematico, poich\u00e9 alcuni dispositivi potrebbero non funzionare bene a temperature estreme.","og_url":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/","og_site_name":"KnowHow","article_published_time":"2023-02-07T12:16:00+00:00","article_modified_time":"2023-02-07T12:16:06+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png","type":"image\/png"}],"author":"Justyna Matuszak","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Justyna Matuszak","Tempo di lettura stimato":"6 minuti","Written by":"Justyna Matuszak"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#article","isPartOf":{"@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/"},"author":{"name":"Justyna Matuszak","@id":"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/person\/0f190c371d7aa3b29340b10882910edb"},"headline":"Comunicazione di dati in ambienti difficili","datePublished":"2023-02-07T12:16:00+00:00","dateModified":"2023-02-07T12:16:06+00:00","mainEntityOfPage":{"@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/"},"wordCount":1179,"publisher":{"@id":"https:\/\/knowhow.distrelec.com\/it\/#organization"},"image":{"@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage"},"thumbnailUrl":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png","articleSection":["Automazione","Internet delle Cose (IoT)","STEM e istruzione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/","url":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/","name":"Comunicazione di dati in ambienti difficili - KnowHow","isPartOf":{"@id":"https:\/\/knowhow.distrelec.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage"},"image":{"@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage"},"thumbnailUrl":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png","datePublished":"2023-02-07T12:16:00+00:00","dateModified":"2023-02-07T12:16:06+00:00","description":"Lo scambio di dati in ambienti difficili pu\u00f2 essere problematico, poich\u00e9 alcuni dispositivi potrebbero non funzionare bene a temperature estreme.","breadcrumb":{"@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#primaryimage","url":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png","contentUrl":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/knowhow.distrelec.com\/it\/automazione\/comunicazione-di-dati-in-ambienti-difficili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/knowhow.distrelec.com\/it\/"},{"@type":"ListItem","position":2,"name":"Comunicazione di dati in ambienti difficili"}]},{"@type":"WebSite","@id":"https:\/\/knowhow.distrelec.com\/it\/#website","url":"https:\/\/knowhow.distrelec.com\/it\/","name":"KnowHow","description":"KnowHow Hub","publisher":{"@id":"https:\/\/knowhow.distrelec.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/knowhow.distrelec.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/knowhow.distrelec.com\/it\/#organization","name":"Distrelec","url":"https:\/\/knowhow.distrelec.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2021\/09\/distrelec_logo.png","contentUrl":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2021\/09\/distrelec_logo.png","width":530,"height":98,"caption":"Distrelec"},"image":{"@id":"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/person\/0f190c371d7aa3b29340b10882910edb","name":"Justyna Matuszak","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/knowhow.distrelec.com\/it\/#\/schema\/person\/image\/9a432b6fa69e68c439c1a2d8acf914c3","url":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2024\/02\/cropped-Justyna-scaled-3-96x96.jpg","contentUrl":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2024\/02\/cropped-Justyna-scaled-3-96x96.jpg","caption":"Justyna Matuszak"},"description":"Justyna, as a Digital Content Writer at Distrelec, is responsible for writing and managing content on KnowHow. She studied Journalism and Social Communication with a specialisation in social media and e-PR. In that time, she participated in journalist internships in Wroclaw (PL) and London. She is passionate about innovations, the digital world and the impact technology has on our lives. Her interests are sport, music and film photography.","sameAs":["http:\/\/www.distrelec.com","https:\/\/uk.linkedin.com\/in\/justyna-matuszak-217b51172"],"url":"https:\/\/knowhow.distrelec.com\/it\/author\/justyna-matusza\/"}]}},"jetpack_featured_media_url":"https:\/\/knowhow.distrelec.com\/wp-content\/uploads\/2023\/01\/Winter-Autota-over-Halley.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/posts\/44244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/comments?post=44244"}],"version-history":[{"count":0,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/posts\/44244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/media\/42497"}],"wp:attachment":[{"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/media?parent=44244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/categories?post=44244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/tags?post=44244"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/knowhow.distrelec.com\/it\/wp-json\/wp\/v2\/coauthors?post=44244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}